{"id":957,"date":"2022-11-29T20:27:07","date_gmt":"2022-11-29T17:27:07","guid":{"rendered":"https:\/\/katiasiqueira.com.br\/?p=957"},"modified":"2022-11-30T02:50:48","modified_gmt":"2022-11-29T23:50:48","slug":"casacor-rio-de-janeiro-2022","status":"publish","type":"post","link":"https:\/\/katiasiqueira.com.br\/en\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/","title":{"rendered":"CASACOR Rio de Janeiro 2022"},"content":{"rendered":"<p><span style=\"color: #333333;\"><strong><em>JACKET RIO<\/em><\/strong> was born just three years after the S\u00e3o Paulo event, in 1991, being the brand&#039;s first franchise, interpreting the Rio way of living...<\/span><\/p>\n<p><span style=\"color: #333333;\"><strong><em>JACKET RIO<\/em><\/strong> reveals the passion for the city and seeks to showcase some of its real estate icons (many of them restored for the exhibitions, such as mansions, urban houses, real estate launches... &nbsp;<\/span><\/p>\n<p><span style=\"color: #333333;\">This year&#039;s exhibition took place in the Brando Barbosa mansion, a mansion located in the Jardim Bot\u00e2nico neighborhood and this space stands out for being surrounded by a garden of approximately 12 thousand m\u00b2 of Atlantic Forest. A true balm in the wonderful city, housing a huge diversity of Atlantic Forest flora. (anthuriums, philodendrons and Adam&#039;s ribs, many exotic and exuberant species).<\/span><\/p>\n<p><span style=\"color: #333333;\">38 spaces designed by architects and designers made up the 2022 edition. The entrance hall was transformed into a beautiful art gallery with works created exclusively for the exhibition. (Designed for the artists at Instituto Brando Barbosa to gather their works, exchange ideas\u2026).<\/span><\/p>\n<p><span style=\"color: #333333;\">Without a doubt visit this <strong><em>JACKET RIO<\/em><\/strong> It was an invitation to a trip to the past through the spaces built with their high ceilings, hardwood details, French doors, huge windows opening to spaces of pure coexistence, balconies, magnificent gardens that lead us to meditation, contemplation of nature , to refuge; which provides us with well-being with the color, ventilation and light that Rio de Janeiro has. The practicality with the use of natural materials such as cotton, linen, sisal, in the comfort of sofas and their cushions, rugs, in the delicacy of bed and bath linen inviting us to take a nap, a good soak in the bathtub; in the aromas that provoke good memories and sharpen our senses. A true biophilic space, leading us to the production of serotonin (happiness hormone), which among its functions is the regulation of heart rate, sleep, appetite, mood, memory and body temperature. I can guarantee you that you will leave feeling refreshed! And already thinking about the 2023 edition.<\/span><\/p>\n<p><span style=\"color: #333333;\">I invite you to see our photo and video gallery!<\/span><\/p>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-xsmall slider row-slider slider-nav-reveal\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: true, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 4000}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO2-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO3-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO4-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO5-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO6-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO7-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO8-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO9-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO10-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO11-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO12-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO13-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO14-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO15-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO16-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO17-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO18-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO19-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO20-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO21-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO23-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO24-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO25-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO26-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO27-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO28-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO29-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-578x1024.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"961,962,964,965,968,969,972,973,977,978,980,983,984,986,989,990,992,995,996,998,1002,1003,1006,1007,1008,1010,1012,1042\" type=\"slider\" col_spacing=\"xsmall\" slider_bullets=\"true\" auto_slide=\"4000\" srcset=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-169x300.jpg 169w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-578x1024.jpg 578w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-768x1362.jpg 768w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-866x1536.jpg 866w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-1155x2048.jpg 1155w, https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/CasaCorRIO22-1-scaled.jpg 1444w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\n<p>&nbsp;<\/p>\n<p><span style=\"color: #333333;\">Did you like it? Want to know more about <strong><em>CASACOR RIO DE JANEIRO? <\/em><\/strong>Access the link: <a style=\"color: #333333;\" href=\"https:\/\/casacor.abril.com.br\/mostras\/rio-de-janeiro\/\">https:\/\/casacor.abril.com.br\/mostras\/rio-de-janeiro\/<\/a><\/span><\/p>\n<div class=\"row row-small row-full-width align-middle align-center\"  id=\"row-1074996881\">\n\n\n\t<div id=\"col-1083816235\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:200%;\"><iframe loading=\"lazy\" title=\"CasaCorRIOv1\" src=\"https:\/\/player.vimeo.com\/video\/776285684?h=169f1b81a3&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1083816235 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -86px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1687126811\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:200%;\"><p><iframe loading=\"lazy\" title=\"CasaCorRIOv2\" src=\"https:\/\/player.vimeo.com\/video\/776285717?h=fbf9429246&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1687126811 > .col-inner {\n  margin: 0px 0px -86px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1777381264\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:200%;\"><p><iframe loading=\"lazy\" title=\"CasaCorRIOv3\" src=\"https:\/\/player.vimeo.com\/video\/776285738?h=f0940d6e3b&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1777381264 > .col-inner {\n  margin: 0px 0px -81px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-598210519\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:200%;\"><p><iframe loading=\"lazy\" title=\"CasaCorRIOv4\" src=\"https:\/\/player.vimeo.com\/video\/776285775?h=edf7a83d11&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-598210519 > .col-inner {\n  margin: 0px 0px -81px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>CASACOR RIO was born just three years after the S\u00e3o Paulo event, in 1991, being the brand&#039;s first franchise, interpreting the Rio way of living.<\/p>","protected":false},"author":1,"featured_media":1060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,29],"tags":[30,36,37],"class_list":["post-957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casacor","category-eventos","tag-casacor","tag-design-de-interiores","tag-rio-de-janeiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira<\/title>\n<meta name=\"description\" content=\"CASACOR RIO nasceu apenas tr\u00eas anos depois do evento paulista, em 1991, sendo a primeira franquia da marca, interpretando o jeito carioca de morar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/katiasiqueira.com.br\/en\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira\" \/>\n<meta property=\"og:description\" content=\"CASACOR RIO nasceu apenas tr\u00eas anos depois do evento paulista, em 1991, sendo a primeira franquia da marca, interpretando o jeito carioca de morar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/katiasiqueira.com.br\/en\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"K\u00e1tia Siqueira\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T17:27:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T23:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1444\" \/>\n\t<meta property=\"og:image:height\" content=\"1446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"katiasiqueira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"katiasiqueira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\"},\"author\":{\"name\":\"katiasiqueira\",\"@id\":\"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775\"},\"headline\":\"CASACOR Rio de Janeiro 2022\",\"datePublished\":\"2022-11-29T17:27:07+00:00\",\"dateModified\":\"2022-11-29T23:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\"},\"wordCount\":505,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg\",\"keywords\":[\"casacor\",\"Design de interiores\",\"rio de janeiro\"],\"articleSection\":[\"CASACOR\",\"Eventos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\",\"url\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\",\"name\":\"CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira\",\"isPartOf\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg\",\"datePublished\":\"2022-11-29T17:27:07+00:00\",\"dateModified\":\"2022-11-29T23:50:48+00:00\",\"author\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775\"},\"description\":\"CASACOR RIO nasceu apenas tr\u00eas anos depois do evento paulista, em 1991, sendo a primeira franquia da marca, interpretando o jeito carioca de morar.\",\"breadcrumb\":{\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage\",\"url\":\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg\",\"contentUrl\":\"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg\",\"width\":1444,\"height\":1446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/katiasiqueira.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASACOR Rio de Janeiro 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/katiasiqueira.com.br\/#website\",\"url\":\"https:\/\/katiasiqueira.com.br\/\",\"name\":\"K\u00e1tia Siqueira\",\"description\":\"Design de Interiores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/katiasiqueira.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775\",\"name\":\"katiasiqueira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g\",\"caption\":\"katiasiqueira\"},\"sameAs\":[\"https:\/\/katiasiqueira.com.br\"],\"url\":\"https:\/\/katiasiqueira.com.br\/en\/author\/katiasiqueira\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira","description":"CASACOR RIO was born just three years after the S\u00e3o Paulo event, in 1991, being the brand&#039;s first franchise, interpreting the Rio way of living.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/katiasiqueira.com.br\/en\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/","og_locale":"en_US","og_type":"article","og_title":"CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira","og_description":"CASACOR RIO nasceu apenas tr\u00eas anos depois do evento paulista, em 1991, sendo a primeira franquia da marca, interpretando o jeito carioca de morar.","og_url":"https:\/\/katiasiqueira.com.br\/en\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/","og_site_name":"K\u00e1tia Siqueira","article_published_time":"2022-11-29T17:27:07+00:00","article_modified_time":"2022-11-29T23:50:48+00:00","og_image":[{"width":1444,"height":1446,"url":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","type":"image\/jpeg"}],"author":"katiasiqueira","twitter_card":"summary_large_image","twitter_misc":{"Written by":"katiasiqueira","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#article","isPartOf":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/"},"author":{"name":"katiasiqueira","@id":"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775"},"headline":"CASACOR Rio de Janeiro 2022","datePublished":"2022-11-29T17:27:07+00:00","dateModified":"2022-11-29T23:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/"},"wordCount":505,"commentCount":0,"image":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","keywords":["casacor","Design de interiores","rio de janeiro"],"articleSection":["CASACOR","Eventos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/","url":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/","name":"CASACOR Rio de Janeiro 2022 - K\u00e1tia Siqueira","isPartOf":{"@id":"https:\/\/katiasiqueira.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage"},"image":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","datePublished":"2022-11-29T17:27:07+00:00","dateModified":"2022-11-29T23:50:48+00:00","author":{"@id":"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775"},"description":"CASACOR RIO was born just three years after the S\u00e3o Paulo event, in 1991, being the brand&#039;s first franchise, interpreting the Rio way of living.","breadcrumb":{"@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#primaryimage","url":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","contentUrl":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","width":1444,"height":1446},{"@type":"BreadcrumbList","@id":"https:\/\/katiasiqueira.com.br\/2022\/11\/29\/casacor-rio-de-janeiro-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/katiasiqueira.com.br\/"},{"@type":"ListItem","position":2,"name":"CASACOR Rio de Janeiro 2022"}]},{"@type":"WebSite","@id":"https:\/\/katiasiqueira.com.br\/#website","url":"https:\/\/katiasiqueira.com.br\/","name":"Katia Siqueira","description":"Interior Design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/katiasiqueira.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/katiasiqueira.com.br\/#\/schema\/person\/601eb330b876d048874810cdc020e775","name":"katiasiqueira","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/695bd393cf6d0f44895a06657bfd7c4476674ac307338cea970b2a0ce0474c31?s=96&d=mm&r=g","caption":"katiasiqueira"},"sameAs":["https:\/\/katiasiqueira.com.br"],"url":"https:\/\/katiasiqueira.com.br\/en\/author\/katiasiqueira\/"}]}},"jetpack_featured_media_url":"https:\/\/katiasiqueira.com.br\/wp-content\/uploads\/2022\/11\/thumb-rio-2-scaled-e1669759703699.jpg","_links":{"self":[{"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/posts\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/comments?post=957"}],"version-history":[{"count":14,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/posts\/957\/revisions"}],"predecessor-version":[{"id":1167,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/posts\/957\/revisions\/1167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/media\/1060"}],"wp:attachment":[{"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/categories?post=957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/katiasiqueira.com.br\/en\/wp-json\/wp\/v2\/tags?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}